{"id":9549,"date":"2022-11-04T14:31:00","date_gmt":"2022-11-04T19:31:00","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=9549"},"modified":"2022-11-03T14:50:55","modified_gmt":"2022-11-03T19:50:55","slug":"bisd-celebrated-red-ribbon-week","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/bisd-celebrated-red-ribbon-week\/","title":{"rendered":"BISD Celebrated Red Ribbon Week\u00a0"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw.jpg\" alt=\"\" class=\"wp-image-9550\" width=\"434\" height=\"169\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw.jpg 1280w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-450x176.jpg 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-768x300.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-760x297.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-518x202.jpg 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-82x32.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-600x234.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2022\/11\/rrw-550x215.jpg 550w\" sizes=\"auto, (max-width: 434px) 100vw, 434px\" \/><\/figure>\n\n\n\n<p>Students and staff across Birdville ISD recently celebrated Red Ribbon Week Oct. 24-30. This year\u2019s theme was, \u201cCelebrate LIFE. Live Drug Free.\u201d\u00a0<\/p>\n\n\n\n<p><a href=\"https:\/\/birdvilleschools.smugmug.com\/BirdvilleISD\/Red-Ribbon-Week-2022\/\">View pictures of various events\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Students and staff across Birdville ISD recently celebrated Red Ribbon Week Oct. 24-30. This year\u2019s theme was, \u201cCelebrate LIFE. Live Drug Free.\u201d\u00a0 View pictures of various events\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[122],"tags":[],"class_list":["post-9549","post","type-post","status-publish","format-standard","hentry","category-red-ribbon-week"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-2u1","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/9549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=9549"}],"version-history":[{"count":1,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/9549\/revisions"}],"predecessor-version":[{"id":9551,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/9549\/revisions\/9551"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=9549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=9549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=9549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}