{"id":7446,"date":"2020-07-23T21:19:38","date_gmt":"2020-07-24T02:19:38","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=7446"},"modified":"2020-07-23T21:19:41","modified_gmt":"2020-07-24T02:19:41","slug":"board-of-trustees-meeting-summary-65","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/board-of-trustees-meeting-summary-65\/","title":{"rendered":"Board of Trustees Meeting Summary"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-1024x683.jpg\" alt=\"Board of Trustees\" class=\"wp-image-5953\" width=\"235\" height=\"156\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-1024x683.jpg 1024w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-450x300.jpg 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-768x512.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-760x507.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-518x345.jpg 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-250x166.jpg 250w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-82x55.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-600x400.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2018\/06\/IMG_1633-550x367.jpg 550w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure><\/div>\n\n\n\n<p>The Board of Trustees met in regular session on Thursday, July 23. The following link will provide you a summary of actions taken at their meeting.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.birdvilleschools.net\/Page\/65904\" target=\"_blank\" rel=\"noreferrer noopener\">&gt; View July 23, 2020&nbsp;e-review<\/a><br><a rel=\"noreferrer noopener\" href=\"https:\/\/birdvilleschools.us9.list-manage.com\/track\/click?u=2411ee053bf8434ee0344c4be&amp;id=16351ed9bb&amp;e=b78b9257fc\" target=\"_blank\">&gt; View Board of Trustees Website<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Board of Trustees met in regular session on Thursday, July 23. The following link will provide you a summary of actions taken at their meeting. &gt; View July 23, 2020&nbsp;e-review&gt; View Board of Trustees Website<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[100],"tags":[],"class_list":["post-7446","post","type-post","status-publish","format-standard","hentry","category-bisdbot"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-1W6","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/7446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=7446"}],"version-history":[{"count":2,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/7446\/revisions"}],"predecessor-version":[{"id":7451,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/7446\/revisions\/7451"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=7446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=7446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=7446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}