{"id":6945,"date":"2020-01-23T20:44:42","date_gmt":"2020-01-24T02:44:42","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=6945"},"modified":"2020-01-23T20:45:43","modified_gmt":"2020-01-24T02:45:43","slug":"board-approves-2020-21-school-calendar","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/board-approves-2020-21-school-calendar\/","title":{"rendered":"Board Approves 2020-21 School Calendar"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1.jpg\" alt=\"2020-21 School Calendar\" class=\"wp-image-6955\" width=\"450\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1.jpg 1700w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-232x300.jpg 232w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-768x994.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-1186x1536.jpg 1186w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-1582x2048.jpg 1582w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-760x984.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-309x400.jpg 309w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-82x106.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-600x777.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2020\/01\/2021Calendar_Page_1-550x712.jpg 550w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/><\/figure>\n\n\n\n<p>On Thursday, January 23, the BISD Board of Trustees approved the 2020-21 School Calendar.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.birdvilleschools.net\/cms\/lib\/TX01000797\/Centricity\/Domain\/1\/2021Calendar.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">Click here to view a PDF version of the 2020\u201321 school calendar. (This link will open in a new window.)<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On Thursday, January 23, the BISD Board of Trustees approved the 2020-21 School Calendar. Click here to view a PDF version of the 2020\u201321 school calendar. (This link will open in a new window.)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26,1],"tags":[],"class_list":["post-6945","post","type-post","status-publish","format-standard","hentry","category-calendar","category-uncategorized"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-1O1","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/6945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=6945"}],"version-history":[{"count":2,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/6945\/revisions"}],"predecessor-version":[{"id":6956,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/6945\/revisions\/6956"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=6945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=6945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=6945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}