{"id":5006,"date":"2017-09-12T08:16:21","date_gmt":"2017-09-12T13:16:21","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=5006"},"modified":"2017-09-12T08:16:21","modified_gmt":"2017-09-12T13:16:21","slug":"lockdown-drill-planned","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/lockdown-drill-planned\/","title":{"rendered":"Lockdown Drill Planned"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5007\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-450x300.jpg 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-768x512.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-1024x683.jpg 1024w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-760x507.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-518x345.jpg 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-250x166.jpg 250w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-82x55.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-600x400.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/09\/shutterstock_385828378-550x367.jpg 550w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p class=\"p1\"><span class=\"s1\">In order to check Birdville ISD\u2019s emergency systems, the District will conduct a districtwide lockdown drill this week. When the drill begins on the campus, an announcement will be made on all District phones indicating BISD is going into a lockdown. At the same time, all doors will be locked and closed.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">As part of the drill, BISD will use the District\u2019s mobile app to notify parents when the drill begins and ends. Birdville\u2019s mobile app is available for free in the Apple and Google stores.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">In a real emergency, a lockdown means students and staff will remain in their locked classrooms until the police give the ALL CLEAR. During a lockdown, no one is allowed in or out of the secured building.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>&nbsp;<\/p>\n<p>Esta semana, el Distrito Escolar Independiente de Birdville (Birdville Independent School District, BISD) realizar\u00e1 un simulacro de confinamiento para poner a prueba sus sistemas de emergencia. Cuando comience el ejercicio, se har\u00e1 el anuncio mediante todos los tel\u00e9fonos del Distrito para indicar que el BISD entra en modo de confinamiento. Todas las puertas se cerrar\u00e1n simult\u00e1neamente con cerrojo.<\/p>\n<p>Como parte del ejercicio, el BISD utilizar\u00e1 la aplicaci\u00f3n m\u00f3vil del Distrito para notificar a los padres sobre el inicio y la culminaci\u00f3n del simulacro. La aplicaci\u00f3n puede obtenerse de manera gratuita en Apple Store y Google Store.<\/p>\n<p>Una emergencia verdadera implica que los estudiantes y el personal de la escuela permanecer\u00e1n confinados bajo llave en sus aulas hasta que la polic\u00eda anuncie el <span class=\"tw-bilingual-translation\" lang=\"es\">final de la alarma<\/span>, indicando con ello que la situaci\u00f3n est\u00e1 bajo control. A nadie se le permite salir del edificio bajo protecci\u00f3n ni ingresar en \u00e9l durante una situaci\u00f3n de confinamiento de emergencia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In order to check Birdville ISD\u2019s emergency systems, the District will conduct a districtwide lockdown drill this week. When the drill begins on the campus, an announcement will be made on all District phones indicating BISD is going into a lockdown. At the same time, all doors will be locked and closed. As part of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[92],"tags":[],"class_list":["post-5006","post","type-post","status-publish","format-standard","hentry","category-bisdalert"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-1iK","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/5006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=5006"}],"version-history":[{"count":1,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/5006\/revisions"}],"predecessor-version":[{"id":5008,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/5006\/revisions\/5008"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=5006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=5006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=5006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}