{"id":4945,"date":"2017-08-24T15:29:24","date_gmt":"2017-08-24T20:29:24","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=4945"},"modified":"2017-08-24T15:29:24","modified_gmt":"2017-08-24T20:29:24","slug":"richland-high-school-student-completes-eagle-scout-project-bisdshines","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/richland-high-school-student-completes-eagle-scout-project-bisdshines\/","title":{"rendered":"Richland High School Student Completes Eagle Scout Project #BISDShines"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Steven Graham, Richland High School student and former North Ridge Middle School student, recently worked with several North Ridge teachers for his Eagle Scout\u00a0project. Ms. Caceres, Mrs. Gorman and Mrs.\u00a0Lord met with Steven several times to listen to his plan and then watch him put it into action.\u00a0For his project, Steven chose to \u201crevitalize\u201d the science shed. After cleaning it out, replacing the flooring and building shelves, he sanded down and painted the outside of the shed.\u00a0They are all proud of Steven and thank him for his hard work and perseverance in completing this task to earn his Eagle Scout. Steven is modeling BISD\u2019s focus on excellence, integrity and service. #BISDShines<\/span><\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4946 \" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-225x300.jpg\" alt=\"\" width=\"283\" height=\"377\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-225x300.jpg 225w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-768x1024.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-760x1013.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-300x400.jpg 300w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-82x109.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-600x800.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1856-e1503606457865-550x733.jpg 550w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4947\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-225x300.jpg\" alt=\"\" width=\"273\" height=\"364\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-225x300.jpg 225w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-768x1024.jpg 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-760x1013.jpg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-300x400.jpg 300w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-82x109.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-600x800.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1857-e1503606393956-550x733.jpg 550w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-4948\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-450x253.png\" alt=\"\" width=\"450\" height=\"253\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-450x253.png 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-768x432.png 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-1024x576.png 1024w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-760x427.png 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-518x291.png 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-82x46.png 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-600x337.png 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921-550x309.png 550w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1921.png 1334w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-4949\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-450x253.png\" alt=\"\" width=\"450\" height=\"253\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-450x253.png 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-768x432.png 768w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-1024x576.png 1024w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-760x427.png 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-518x291.png 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-82x46.png 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-600x337.png 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922-550x309.png 550w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_1922.png 1334w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Steven Graham, Richland High School student and former North Ridge Middle School student, recently worked with several North Ridge teachers for his Eagle Scout\u00a0project. Ms. Caceres, Mrs. Gorman and Mrs.\u00a0Lord met with Steven several times to listen to his plan and then watch him put it into action.\u00a0For his project, Steven chose to \u201crevitalize\u201d the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[104,17],"tags":[],"class_list":["post-4945","post","type-post","status-publish","format-standard","hentry","category-bisdshines","category-richland-high-school"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-1hL","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=4945"}],"version-history":[{"count":1,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4945\/revisions"}],"predecessor-version":[{"id":4952,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4945\/revisions\/4952"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=4945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=4945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=4945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}