{"id":4401,"date":"2017-03-08T12:15:02","date_gmt":"2017-03-08T18:15:02","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=4401"},"modified":"2017-03-08T12:23:40","modified_gmt":"2017-03-08T18:23:40","slug":"remember-to-spring-forward-sunday-march-12","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/remember-to-spring-forward-sunday-march-12\/","title":{"rendered":"Remember to Spring Forward March 12"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4402\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017.jpg\" alt=\"\" width=\"450\" height=\"197\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017.jpg 720w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017-450x197.jpg 450w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017-518x227.jpg 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017-82x36.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017-600x263.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/03\/SpringForward2017-550x241.jpg 550w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[180],"tags":[],"class_list":["post-4401","post","type-post","status-publish","format-standard","hentry","category-spring-forward"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-18Z","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=4401"}],"version-history":[{"count":2,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4401\/revisions"}],"predecessor-version":[{"id":4405,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4401\/revisions\/4405"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=4401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=4401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=4401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}