{"id":4212,"date":"2017-01-11T15:17:51","date_gmt":"2017-01-11T21:17:51","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=4212"},"modified":"2017-01-11T15:59:16","modified_gmt":"2017-01-11T21:59:16","slug":"2017-elementary-battle-of-the-books-and-awards-ceremony","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/2017-elementary-battle-of-the-books-and-awards-ceremony\/","title":{"rendered":"2017 Elementary Battle of the Books and Awards Ceremony"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4213 aligncenter\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-397x300.png\" alt=\"Picture1\" width=\"397\" height=\"300\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-397x300.png 397w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-518x392.png 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-82x62.png 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-131x98.png 131w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1-550x416.png 550w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2017\/01\/Picture1.png 570w\" sizes=\"auto, (max-width: 397px) 100vw, 397px\" \/><\/p>\n<p><em>Birdville Independent School District<\/em><\/p>\n<p><em>Cordially invites you to the <\/em><\/p>\n<p><strong>2017\u00a0<\/strong><strong>Elementary\u00a0<\/strong><strong>Battle of the Books\u00a0<\/strong><strong>and\u00a0<\/strong><strong>Awards Ceremony<\/strong><\/p>\n<p><em>Thursday, January 26, 2017<\/em><\/p>\n<p><em>8:45 a.m.-12:00 p.m.<\/em><\/p>\n<p><em>W. G. Thomas, Jr. Coliseum<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Birdville Independent School District Cordially invites you to the 2017\u00a0Elementary\u00a0Battle of the Books\u00a0and\u00a0Awards Ceremony Thursday, January 26, 2017 8:45 a.m.-12:00 p.m. W. G. Thomas, Jr. Coliseum<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[78],"tags":[],"class_list":["post-4212","post","type-post","status-publish","format-standard","hentry","category-battle-of-the-books"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-15W","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=4212"}],"version-history":[{"count":2,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4212\/revisions"}],"predecessor-version":[{"id":4221,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/4212\/revisions\/4221"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=4212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=4212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=4212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}