{"id":3557,"date":"2016-05-24T15:02:47","date_gmt":"2016-05-24T21:02:47","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=3557"},"modified":"2016-05-24T15:02:47","modified_gmt":"2016-05-24T21:02:47","slug":"children-at-risk-2016-annual-school-rankings-announced","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/children-at-risk-2016-annual-school-rankings-announced\/","title":{"rendered":"Children at Risk 2016 Annual School Rankings Announced"},"content":{"rendered":"<p><a href=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3559 aligncenter\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-400x300.jpeg\" alt=\"Fort Worth Area 2\" width=\"400\" height=\"300\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-400x300.jpeg 400w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-1024x768.jpeg 1024w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-760x570.jpeg 760w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-518x389.jpeg 518w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-82x62.jpeg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-131x98.jpeg 131w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-600x450.jpeg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/Fort-Worth-Area-2-550x413.jpeg 550w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Congratulations to Smithfield Middle School for being ranked #2 in the Fort Worth area in the Children at Risk 2016 Annual School Rankings. Schools are measured by achievement indicators, performance indicators, growth indicators, and college readiness.<\/p>\n<p><a href=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/05\/2016-CHILDREN-AT-RISK-Annual-School-Rankings-002.pdf\">&gt; Learn More<\/a><\/p>\n<p><a href=\"http:\/\/childrenatrisk.org\/content\/\">&gt; Children at Risk Website<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Congratulations to Smithfield Middle School for being ranked #2 in the Fort Worth area in the Children at Risk 2016 Annual School Rankings. Schools are measured by achievement indicators, performance indicators, growth indicators, and college readiness. &gt; Learn More &gt; Children at Risk Website<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[104,131,33],"tags":[],"class_list":["post-3557","post","type-post","status-publish","format-standard","hentry","category-bisdshines","category-wearebirdvilleisd","category-smithfield-middle-school"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-Vn","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=3557"}],"version-history":[{"count":1,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3557\/revisions"}],"predecessor-version":[{"id":3560,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3557\/revisions\/3560"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=3557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=3557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=3557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}