{"id":3015,"date":"2016-01-07T08:36:50","date_gmt":"2016-01-07T14:36:50","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/?p=3015"},"modified":"2016-01-07T08:38:45","modified_gmt":"2016-01-07T14:38:45","slug":"north-richland-middle-school-groundbreaking","status":"publish","type":"post","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/north-richland-middle-school-groundbreaking\/","title":{"rendered":"North Richland Middle School Groundbreaking"},"content":{"rendered":"<p><a href=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3016 aligncenter\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite.jpg\" alt=\"invite\" width=\"450\" height=\"630\" srcset=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite.jpg 713w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite-214x300.jpg 214w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite-286x400.jpg 286w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite-82x115.jpg 82w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite-600x840.jpg 600w, https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2016\/01\/invite-550x770.jpg 550w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[72],"tags":[],"class_list":["post-3015","post","type-post","status-publish","format-standard","hentry","category-north-richland-middle"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p76FL9-MD","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=3015"}],"version-history":[{"count":2,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3015\/revisions"}],"predecessor-version":[{"id":3018,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/posts\/3015\/revisions\/3018"}],"wp:attachment":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media?parent=3015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/categories?post=3015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/tags?post=3015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}