{"id":1691,"date":"2015-03-03T13:56:39","date_gmt":"2015-03-03T19:56:39","guid":{"rendered":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2015\/03\/15header.jpg"},"modified":"2015-03-03T13:56:39","modified_gmt":"2015-03-03T19:56:39","slug":"15header","status":"inherit","type":"attachment","link":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/15header\/","title":{"rendered":"15header"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-1691","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a76FL9-rh","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2015\/03\/15header.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"116\" src=\"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2015\/03\/15header.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2550,"height":657,"file":"2015\/03\/15header.jpg","image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"sizes":{}},"post":null,"source_url":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-content\/uploads\/2015\/03\/15header.jpg","_links":{"self":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media\/1691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.birdvilleschools.net\/district\/wordpress\/wp-json\/wp\/v2\/comments?post=1691"}]}}